{"id":16439,"date":"2020-03-24T17:28:43","date_gmt":"2020-03-24T16:28:43","guid":{"rendered":"https:\/\/www.geniu.com\/de\/?p=16439"},"modified":"2024-11-20T16:34:31","modified_gmt":"2024-11-20T15:34:31","slug":"covid-19-testkapazitaet-bereits-ueber-dem-limit","status":"publish","type":"post","link":"https:\/\/www.geniu.com\/de\/covid-19-testkapazitaet-bereits-ueber-dem-limit\/","title":{"rendered":"Covid-19-Testkapazit\u00e4t bereits \u00fcber dem \u201eLimit\u201c"},"content":{"rendered":"\n<p><strong>Das Testen und die Separierung von Corona-Infizierten ist ein wesentlicher Teil der Eind\u00e4mmungsstrategie. Die Testkapazit\u00e4t ist daher von entscheidender Bedeutung. Verschiedene Sch\u00e4tzwerte zur Testkapazit\u00e4t kursieren durch die Medien. Keine davon scheint ann\u00e4herungsweise richtig zu sein \u2013 denn keiner kann die Kapazit\u00e4t aktuell wirklich kennen. Eine Berechnung von Geniu Lab Institute zeigt jedoch, dass der tats\u00e4chliche Test-Output bereits \u00fcber den gesch\u00e4tzten Werten \u2013 also schon \u201e\u00fcber dem Limit\u201c liegt.<\/strong><\/p>\n\n\n\n<p>Covid-19 breitet sich um die Welt rasant aus. Auch in Deutschland liegt das Wachstum bei \u00fcber 20%. Ein wesentlicher Teil der Eind\u00e4mmungsstrategie ist das Testen und die Separierung von Corona-Infizierten ist. Daher ist Testkapazit\u00e4t von entscheidender Bedeutung. Der Generaldirektor der WHO-Director Dr. Ghebreyesus beschreibt die Herausforderung wie folgt:\u00a0<em>\u201eWir k\u00f6nnen die Pandemie nicht stoppen, wenn wir nicht wissen wer infiziert ist. Deshalb die einfache Bitte an alle: testen, testen, testen!\u201c<\/em><sup>6<\/sup>\u00a0\u00dcber Deutschland wird berichtet, dass \u00fcberdurchschnittlich viel getestet wird. Aber wie lange kann die Zahl der zu testenden Personen noch steigen, bis das Limit erreicht ist?<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Keiner kennt die tats\u00e4chliche Kapazit\u00e4t<\/h5>\n\n\n\n<p>Die Gesellschaft f\u00fcr Virologie gibt auf ihrer Internetseite 54 Organisationen<sup>7<\/sup>, d.h. Universit\u00e4tskliniken, nicht-universit\u00e4re Einrichtungen aus dem \u00d6ffentlichen Gesundheitsdienst und einige Privatlabore an, die SARS-CoV-S PCR Tests anbieten. Insgesamt wird vermutet, dass es ca. 200 bis 300 Labore<sup>8<\/sup>&nbsp;gibt. Bisher besteht jedoch kein System, das zentral die Testkapazit\u00e4ten erfasst.<\/p>\n\n\n\n<p>Dennoch werden in verschiedenen Medien Aussagen von Personen zur Testkapazit\u00e4t zitiert bzw. live dar\u00fcber berichtet. Darunter vom Bundesgesundheitsminister Spahn, dem Chef des Robert Koch-Instituts (RKI), Lothar Wieler oder dem Sprecher des Bundesverbands der deutschen Labor\u00e4rzte (BDL). Die Angaben zur Testkapazit\u00e4t liegen demnach zwischen 12.000 und 30.000 pro Tag oder 84.000 und 200.000 pro Woche. Aber kann dies wirklich stimmen?<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Anzahl durchgef\u00fchrter Tests als Indikator f\u00fcr die Kapazit\u00e4t<\/h5>\n\n\n\n<p>M\u00f6glich ist es die Anzahl der durchgef\u00fchrten Tests als Indikator f\u00fcr die Kapazit\u00e4t zu betrachten. Diese kann aus der Anzahl der durch Labortests best\u00e4tigten Infizierten pro Tag und dem Anteil an positiv Getesteten berechnet werden. Die Anzahl der Infizierten wird t\u00e4glich durch das RKI ermittelt. Zum Anteil der positiv Getesteten liegen Werte sowohl aus Deutschland als auch zur \u00dcberpr\u00fcfung aus anderen L\u00e4ndern vor. Laut Gesundheitsverwaltung Berlin lag der Anteil in der KW 11 beispielsweise bei 4,3%<sup>9<\/sup>. Ein \u00e4hnlicher Wert von 4,9% hat die britische Gesundheitsbeh\u00f6rde NHS mit Stand 18. M\u00e4rz gemeldet.<sup>10<\/sup>\u00a0Ein niedrigerer Wert von 2,7% wird von der s\u00fcdkoreanischen KCDC berichtet.<sup>10<\/sup>\u00a0Dies ist wahrscheinlich darauf zur\u00fcckzuf\u00fchren, dass in S\u00fcdkorea noch umfangreicher als in Deutschland getestet wird.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Schon jetzt am Limit<\/h5>\n\n\n\n<p>Wenn wir einen Wert von 4% f\u00fcr die Anzahl von positiv getesteten annehmen, dann liegt die Anzahl von durchgef\u00fchrten bereits \u00fcber 100.000 pro Tag und damit bereits deutlich \u00fcber dem h\u00f6chsten \u201eKapazit\u00e4tswert\u201c von 30.000 pro Tag \u2013 also deutlich \u201e\u00fcber dem Limit\u201c! Daher ist es nicht verwunderlich, wenn viele Labore \u00fcber massive \u00dcberlastung klagen. Wenn sich die Pandemie folglich weiterhin mit 20% pro Tag ausbreitet, wird es f\u00fcr die Labore eine extreme Herausforderung. Daher ist nicht nur die Politik gefragt, sondern ein koordiniertes Handeln, um die Verf\u00fcgbarkeit von Ger\u00e4ten und Materialien sicherzustellen und durch Prozessoptimierungen z.B.\u00a0<a href=\"https:\/\/www.geniu.com\/de\/2020\/mit-lean-management-die-corona-testkapazitaet-steigern\" target=\"_blank\" rel=\"noreferrer noopener\" title=\"Weitere Informationen\">mit Hilfe von Lean Management-Techniken die Kapazit\u00e4ten bestm\u00f6glich zu nutzen<\/a>.<\/p>\n\n\n\n<p>Quellen:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"has-small-font-size\"><sup>1<\/sup>\u00a0Bundesverbands der deutschen Labor\u00e4rzte [BDL] (berichtet im Bayerischen Rundfunk am 18.03.2020)<\/li>\n\n\n\n<li class=\"has-small-font-size\"><sup>2<\/sup>\u00a0Aussage von Bundesgesuchtheitsminister Jens Spahn bei \u201ePhoenix vor Ort\u201c (Live) um 14 Uhr am 23.03.2020: 200.000 pro Woche, d.h. ca. 28.500 pro Tag<\/li>\n\n\n\n<li class=\"has-small-font-size\"><sup>3<\/sup>\u00a0Robert Koch-Institut [RKI] (berichtet im RBB am 18.03.2020 von Kapazit\u00e4t von 160.000 pro Woche, d.h. ca. 23.000 pro Woche)<\/li>\n\n\n\n<li class=\"has-small-font-size\"><sup>4<\/sup>\u00a0Kassen\u00e4rztliche Bundesvereinigung [KBV] (berichtet in der FAZ am 14.03.2020)<\/li>\n\n\n\n<li class=\"has-small-font-size\"><sup>5<\/sup>\u00a0Anzahl durchgef\u00fchrter Tests berechnet mit der Anzahl positive getesteter von ca. 4% (basierend auf aktuellen Werten von NHS, KBV, Gesundheitsverwaltung Berlin), best\u00e4tigt f\u00fcr KW 10 und 11 durch Fallzahlen der KBV<\/li>\n\n\n\n<li class=\"has-small-font-size\"><sup>6<\/sup>\u00a0Bericht von ARD Extra am 19.03.2020<\/li>\n\n\n\n<li class=\"has-small-font-size\"><sup>7<\/sup>\u00a0Link abgerufen am 24.03.2020 unter www.g-f-v.org\/node\/1233<\/li>\n\n\n\n<li class=\"has-small-font-size\"><sup>8<\/sup>\u00a0Bundesverbands der deutschen Labor\u00e4rzte (BDL), berichtet am 18.03.2020 auf der Internetseite des Best regards (\u201eCorona-Tests: Labore am Limit\u201c)<\/li>\n\n\n\n<li class=\"has-small-font-size\"><sup>9<\/sup>\u00a0Der RBB berichtete am 18.03.2020 im Beitrag \u201eWeniger als f\u00fcnf Prozent der Tests in Berliner Laboren positiv\u201c dar\u00fcber.<\/li>\n\n\n\n<li class=\"has-small-font-size\"><sup>10<\/sup>\u00a0Der Spiegel berichtete am 19.03.2020 im Beitrag \u201eWarum ist die Todesrate in Deutschland niedriger?\u201c dar\u00fcber.<\/li>\n<\/ul>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Testen und die Separierung von Corona-Infizierten ist ein wesentlicher Teil der Eind\u00e4mmungsstrategie. Die Testkapazit\u00e4t ist daher von entscheidender Bedeutung. Verschiedene Sch\u00e4tzwerte zur Testkapazit\u00e4t kursieren durch die Medien. Keine davon scheint ann\u00e4herungsweise richtig zu sein \u2013 denn keiner kann die Kapazit\u00e4t aktuell wirklich kennen. Eine Berechnung von Geniu Lab Institute zeigt jedoch, dass der tats\u00e4chliche [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":16440,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-16439","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-unkategorisiert"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Covid-19-Testkapazit\u00e4t bereits \u00fcber dem \u201eLimit\u201c | Geniu<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.geniu.com\/de\/covid-19-testkapazitaet-bereits-ueber-dem-limit\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Covid-19-Testkapazit\u00e4t bereits \u00fcber dem \u201eLimit\u201c | Geniu\" \/>\n<meta property=\"og:description\" content=\"Das Testen und die Separierung von Corona-Infizierten ist ein wesentlicher Teil der Eind\u00e4mmungsstrategie. Die Testkapazit\u00e4t ist daher von entscheidender Bedeutung. Verschiedene Sch\u00e4tzwerte zur Testkapazit\u00e4t kursieren durch die Medien. Keine davon scheint ann\u00e4herungsweise richtig zu sein \u2013 denn keiner kann die Kapazit\u00e4t aktuell wirklich kennen. Eine Berechnung von Geniu Lab Institute zeigt jedoch, dass der tats\u00e4chliche [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.geniu.com\/de\/covid-19-testkapazitaet-bereits-ueber-dem-limit\/\" \/>\n<meta property=\"og:site_name\" content=\"Geniu\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Geniu-1574654296173059\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-24T16:28:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-20T15:34:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.geniu.com\/wp-content\/uploads\/2020\/03\/geniu_covid-19-testkapazitaet.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"homepage_elias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"homepage_elias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.geniu.com\\\/de\\\/covid-19-testkapazitaet-bereits-ueber-dem-limit\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.geniu.com\\\/de\\\/covid-19-testkapazitaet-bereits-ueber-dem-limit\\\/\"},\"author\":{\"name\":\"homepage_elias\",\"@id\":\"https:\\\/\\\/www.geniu.com\\\/de\\\/#\\\/schema\\\/person\\\/4bb4c41f1269e50e7f76278d09c46a2f\"},\"headline\":\"Covid-19-Testkapazit\u00e4t bereits \u00fcber dem \u201eLimit\u201c\",\"datePublished\":\"2020-03-24T16:28:43+00:00\",\"dateModified\":\"2024-11-20T15:34:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.geniu.com\\\/de\\\/covid-19-testkapazitaet-bereits-ueber-dem-limit\\\/\"},\"wordCount\":703,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.geniu.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geniu.com\\\/de\\\/covid-19-testkapazitaet-bereits-ueber-dem-limit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.geniu.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/geniu_covid-19-testkapazitaet.png\",\"articleSection\":[\"Unkategorisiert\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.geniu.com\\\/de\\\/covid-19-testkapazitaet-bereits-ueber-dem-limit\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.geniu.com\\\/de\\\/covid-19-testkapazitaet-bereits-ueber-dem-limit\\\/\",\"url\":\"https:\\\/\\\/www.geniu.com\\\/de\\\/covid-19-testkapazitaet-bereits-ueber-dem-limit\\\/\",\"name\":\"Covid-19-Testkapazit\u00e4t bereits \u00fcber dem \u201eLimit\u201c | Geniu\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.geniu.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.geniu.com\\\/de\\\/covid-19-testkapazitaet-bereits-ueber-dem-limit\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geniu.com\\\/de\\\/covid-19-testkapazitaet-bereits-ueber-dem-limit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.geniu.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/geniu_covid-19-testkapazitaet.png\",\"datePublished\":\"2020-03-24T16:28:43+00:00\",\"dateModified\":\"2024-11-20T15:34:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.geniu.com\\\/de\\\/covid-19-testkapazitaet-bereits-ueber-dem-limit\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.geniu.com\\\/de\\\/covid-19-testkapazitaet-bereits-ueber-dem-limit\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.geniu.com\\\/de\\\/covid-19-testkapazitaet-bereits-ueber-dem-limit\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.geniu.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/geniu_covid-19-testkapazitaet.png\",\"contentUrl\":\"https:\\\/\\\/www.geniu.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/geniu_covid-19-testkapazitaet.png\",\"width\":800,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.geniu.com\\\/de\\\/covid-19-testkapazitaet-bereits-ueber-dem-limit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.geniu.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Covid-19-Testkapazit\u00e4t bereits \u00fcber dem \u201eLimit\u201c\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.geniu.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.geniu.com\\\/de\\\/\",\"name\":\"Geniu\",\"description\":\"Weiterbildung und Beratung f\u00fcr Labore\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.geniu.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.geniu.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.geniu.com\\\/de\\\/#organization\",\"name\":\"Geniu GmbH\",\"alternateName\":\"Geniu\",\"url\":\"https:\\\/\\\/www.geniu.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.geniu.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Geniu GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geniu.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Geniu-1574654296173059\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/geniu-gmbh\",\"https:\\\/\\\/www.xing.com\\\/companies\\\/geniu?literal=Geniu\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCotSWDP-a-Lbn2o0KbOpbBA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.geniu.com\\\/de\\\/#\\\/schema\\\/person\\\/4bb4c41f1269e50e7f76278d09c46a2f\",\"name\":\"homepage_elias\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c171f0b53bdd1a59de68d61b5b28e3caab705357f5ff5f20a0f2e4a02bd7e62?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c171f0b53bdd1a59de68d61b5b28e3caab705357f5ff5f20a0f2e4a02bd7e62?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c171f0b53bdd1a59de68d61b5b28e3caab705357f5ff5f20a0f2e4a02bd7e62?s=96&d=mm&r=g\",\"caption\":\"homepage_elias\"},\"sameAs\":[\"https:\\\/\\\/www.geniu.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Covid-19-Testkapazit\u00e4t bereits \u00fcber dem \u201eLimit\u201c | Geniu","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.geniu.com\/de\/covid-19-testkapazitaet-bereits-ueber-dem-limit\/","og_locale":"de_DE","og_type":"article","og_title":"Covid-19-Testkapazit\u00e4t bereits \u00fcber dem \u201eLimit\u201c | Geniu","og_description":"Das Testen und die Separierung von Corona-Infizierten ist ein wesentlicher Teil der Eind\u00e4mmungsstrategie. Die Testkapazit\u00e4t ist daher von entscheidender Bedeutung. Verschiedene Sch\u00e4tzwerte zur Testkapazit\u00e4t kursieren durch die Medien. Keine davon scheint ann\u00e4herungsweise richtig zu sein \u2013 denn keiner kann die Kapazit\u00e4t aktuell wirklich kennen. Eine Berechnung von Geniu Lab Institute zeigt jedoch, dass der tats\u00e4chliche [&hellip;]","og_url":"https:\/\/www.geniu.com\/de\/covid-19-testkapazitaet-bereits-ueber-dem-limit\/","og_site_name":"Geniu","article_publisher":"https:\/\/www.facebook.com\/Geniu-1574654296173059","article_published_time":"2020-03-24T16:28:43+00:00","article_modified_time":"2024-11-20T15:34:31+00:00","og_image":[{"width":800,"height":450,"url":"https:\/\/www.geniu.com\/wp-content\/uploads\/2020\/03\/geniu_covid-19-testkapazitaet.png","type":"image\/png"}],"author":"homepage_elias","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"homepage_elias","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.geniu.com\/de\/covid-19-testkapazitaet-bereits-ueber-dem-limit\/#article","isPartOf":{"@id":"https:\/\/www.geniu.com\/de\/covid-19-testkapazitaet-bereits-ueber-dem-limit\/"},"author":{"name":"homepage_elias","@id":"https:\/\/www.geniu.com\/de\/#\/schema\/person\/4bb4c41f1269e50e7f76278d09c46a2f"},"headline":"Covid-19-Testkapazit\u00e4t bereits \u00fcber dem \u201eLimit\u201c","datePublished":"2020-03-24T16:28:43+00:00","dateModified":"2024-11-20T15:34:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.geniu.com\/de\/covid-19-testkapazitaet-bereits-ueber-dem-limit\/"},"wordCount":703,"commentCount":0,"publisher":{"@id":"https:\/\/www.geniu.com\/de\/#organization"},"image":{"@id":"https:\/\/www.geniu.com\/de\/covid-19-testkapazitaet-bereits-ueber-dem-limit\/#primaryimage"},"thumbnailUrl":"https:\/\/www.geniu.com\/wp-content\/uploads\/2020\/03\/geniu_covid-19-testkapazitaet.png","articleSection":["Unkategorisiert"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.geniu.com\/de\/covid-19-testkapazitaet-bereits-ueber-dem-limit\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.geniu.com\/de\/covid-19-testkapazitaet-bereits-ueber-dem-limit\/","url":"https:\/\/www.geniu.com\/de\/covid-19-testkapazitaet-bereits-ueber-dem-limit\/","name":"Covid-19-Testkapazit\u00e4t bereits \u00fcber dem \u201eLimit\u201c | Geniu","isPartOf":{"@id":"https:\/\/www.geniu.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.geniu.com\/de\/covid-19-testkapazitaet-bereits-ueber-dem-limit\/#primaryimage"},"image":{"@id":"https:\/\/www.geniu.com\/de\/covid-19-testkapazitaet-bereits-ueber-dem-limit\/#primaryimage"},"thumbnailUrl":"https:\/\/www.geniu.com\/wp-content\/uploads\/2020\/03\/geniu_covid-19-testkapazitaet.png","datePublished":"2020-03-24T16:28:43+00:00","dateModified":"2024-11-20T15:34:31+00:00","breadcrumb":{"@id":"https:\/\/www.geniu.com\/de\/covid-19-testkapazitaet-bereits-ueber-dem-limit\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.geniu.com\/de\/covid-19-testkapazitaet-bereits-ueber-dem-limit\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.geniu.com\/de\/covid-19-testkapazitaet-bereits-ueber-dem-limit\/#primaryimage","url":"https:\/\/www.geniu.com\/wp-content\/uploads\/2020\/03\/geniu_covid-19-testkapazitaet.png","contentUrl":"https:\/\/www.geniu.com\/wp-content\/uploads\/2020\/03\/geniu_covid-19-testkapazitaet.png","width":800,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/www.geniu.com\/de\/covid-19-testkapazitaet-bereits-ueber-dem-limit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.geniu.com\/de\/"},{"@type":"ListItem","position":2,"name":"Covid-19-Testkapazit\u00e4t bereits \u00fcber dem \u201eLimit\u201c"}]},{"@type":"WebSite","@id":"https:\/\/www.geniu.com\/de\/#website","url":"https:\/\/www.geniu.com\/de\/","name":"Geniu","description":"Weiterbildung und Beratung f\u00fcr Labore","publisher":{"@id":"https:\/\/www.geniu.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.geniu.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.geniu.com\/de\/#organization","name":"Geniu GmbH","alternateName":"Geniu","url":"https:\/\/www.geniu.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.geniu.com\/de\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Geniu GmbH"},"image":{"@id":"https:\/\/www.geniu.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Geniu-1574654296173059","https:\/\/www.linkedin.com\/company\/geniu-gmbh","https:\/\/www.xing.com\/companies\/geniu?literal=Geniu","https:\/\/www.youtube.com\/channel\/UCotSWDP-a-Lbn2o0KbOpbBA"]},{"@type":"Person","@id":"https:\/\/www.geniu.com\/de\/#\/schema\/person\/4bb4c41f1269e50e7f76278d09c46a2f","name":"homepage_elias","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/9c171f0b53bdd1a59de68d61b5b28e3caab705357f5ff5f20a0f2e4a02bd7e62?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9c171f0b53bdd1a59de68d61b5b28e3caab705357f5ff5f20a0f2e4a02bd7e62?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9c171f0b53bdd1a59de68d61b5b28e3caab705357f5ff5f20a0f2e4a02bd7e62?s=96&d=mm&r=g","caption":"homepage_elias"},"sameAs":["https:\/\/www.geniu.com"]}]}},"jetpack_featured_media_url":"https:\/\/www.geniu.com\/wp-content\/uploads\/2020\/03\/geniu_covid-19-testkapazitaet.png","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.geniu.com\/de\/wp-json\/wp\/v2\/posts\/16439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.geniu.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.geniu.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.geniu.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.geniu.com\/de\/wp-json\/wp\/v2\/comments?post=16439"}],"version-history":[{"count":0,"href":"https:\/\/www.geniu.com\/de\/wp-json\/wp\/v2\/posts\/16439\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.geniu.com\/de\/wp-json\/wp\/v2\/media\/16440"}],"wp:attachment":[{"href":"https:\/\/www.geniu.com\/de\/wp-json\/wp\/v2\/media?parent=16439"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.geniu.com\/de\/wp-json\/wp\/v2\/categories?post=16439"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.geniu.com\/de\/wp-json\/wp\/v2\/tags?post=16439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}