{"id":97370,"date":"2025-11-29T00:10:56","date_gmt":"2025-11-28T23:10:56","guid":{"rendered":"https:\/\/www.geniu.com\/?post_type=tribe_events&#038;p=97370"},"modified":"2025-11-29T00:10:56","modified_gmt":"2025-11-28T23:10:56","slug":"ki-im-labor-webinar-2026-09","status":"publish","type":"tribe_events","link":"https:\/\/www.geniu.com\/de\/veranstaltung\/ki-im-labor-webinar-2026-09\/","title":{"rendered":"KI im Labor \u2013 Webinar"},"content":{"rendered":"<p>K\u00fcnstliche Intelligenz (KI) er\u00f6ffnet Laboren v\u00f6llig neue M\u00f6glichkeiten \u2013 von intelligenter Datenauswertung \u00fcber automatisierte Prozesssteuerung bis hin zu Assistenzsystemen, die Mitarbeitende entlasten. Doch welche Anwendungen sind heute schon sinnvoll im Labor einsetzbar, wo liegen die Grenzen, und wie startet man am besten? Dieses Webinar bietet einen praxisnahen \u00dcberblick \u00fcber KI im Labor \u2013 inklusive Anwendungsbeispielen. Zudem erhalten Sie einen \u00dcberblick \u00fcber Geniu\u2019s Beratungsdienstleistungen rund um KI und Digitalisierung im Labor, die Ihnen helfen, Potenziale systematisch zu erkennen und umzusetzen.<\/p>\n<h4>Ziel des Webinars<\/h4>\n<p>Ziel des Webinars ist es, Ihnen einen praxisnahen \u00dcberblick \u00fcber den aktuellen Stand von K\u00fcnstlicher Intelligenz im Labor zu geben. Sie erfahren, wo KI-Technologien heute bereits eingesetzt werden, welche Anwendungsbeispiele aus Laboren es gibt und welche Potenziale und Grenzen dabei zu beachten sind. Dar\u00fcber hinaus erhalten Sie einen Einblick in aktuelle Entwicklungen von KI-Assistenten f\u00fcr Labore sowie in Vorgehensweisen zur erfolgreichen Einf\u00fchrung solcher Technologien.<\/p>\n<h4 class=\"fusion-responsive-typography-calculated\" data-fontsize=\"14\" data-lineheight=\"25.2px\">Zielgruppe<\/h4>\n<p>Das Webinar richtet sich an F\u00fchrungskr\u00e4fte und Mitarbeitende aus Laboren sowie Digitalisierungs- und Qualit\u00e4tsverantwortliche die verstehen m\u00f6chten, wie KI und Digitalisierung die Laborarbeit ver\u00e4ndern \u2013 und welche Chancen sich daraus f\u00fcr Effizienz, Datenqualit\u00e4t und Entscheidungsprozesse ergeben.<\/p>\n<h4 class=\"fusion-responsive-typography-calculated\" data-fontsize=\"14\" data-lineheight=\"25.2px\">Referent<\/h4>\n<p>Dr. Wolf-Christian Gerstner ist Gr\u00fcnder und Gesch\u00e4ftsf\u00fchrer von Geniu, spezialisiert auf Schulungen und Beratung f\u00fcr Labore. Neben Studium und Promotion der Betriebswirtschaftslehre studierte er zus\u00e4tzlich Informatik und arbeitete f\u00fcr einen ERP-Systemanbieter. Er hat Erfahrungen aus zahlreichen Projekten im Bereich Digitalisierung und Automatisierung im Labor.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>K\u00fcnstliche Intelligenz (KI) er\u00f6ffnet Laboren v\u00f6llig neue M\u00f6glichkeiten \u2013 von intelligenter Datenauswertung \u00fcber automatisierte Prozesssteuerung bis hin zu Assistenzsystemen, die Mitarbeitende entlasten. Doch welche Anwendungen sind heute schon sinnvoll im Labor einsetzbar, wo liegen die Grenzen, und wie startet man am besten? Dieses Webinar bietet einen praxisnahen \u00dcberblick \u00fcber KI im Labor \u2013 inklusive Anwendungsbeispielen. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":96114,"template":"","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[30],"class_list":["post-97370","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-webinar","cat_webinar"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>KI im Labor \u2013 Webinar | Geniu<\/title>\n<meta name=\"description\" content=\"KI im Labor verstehen und nutzen: Wie K\u00fcnstliche Intelligenz Effizienz, Datenqualit\u00e4t und Entscheidungsprozesse verbessert.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.geniu.com\/de\/veranstaltung\/ki-im-labor-webinar-2026-09\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"KI im Labor \u2013 Webinar | Geniu\" \/>\n<meta property=\"og:description\" content=\"KI im Labor verstehen und nutzen: Wie K\u00fcnstliche Intelligenz Effizienz, Datenqualit\u00e4t und Entscheidungsprozesse verbessert.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.geniu.com\/de\/veranstaltung\/ki-im-labor-webinar-2026-09\/\" \/>\n<meta property=\"og:site_name\" content=\"Geniu\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Geniu-1574654296173059\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.geniu.com\/wp-content\/uploads\/2025\/10\/image-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1052\" \/>\n\t<meta property=\"og:image:height\" content=\"676\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.geniu.com\\\/de\\\/veranstaltung\\\/ki-im-labor-webinar-2026-09\\\/\",\"url\":\"https:\\\/\\\/www.geniu.com\\\/de\\\/veranstaltung\\\/ki-im-labor-webinar-2026-09\\\/\",\"name\":\"KI im Labor \u2013 Webinar | Geniu\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.geniu.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.geniu.com\\\/de\\\/veranstaltung\\\/ki-im-labor-webinar-2026-09\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geniu.com\\\/de\\\/veranstaltung\\\/ki-im-labor-webinar-2026-09\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.geniu.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/image-1.png\",\"datePublished\":\"2025-11-28T23:10:56+00:00\",\"description\":\"KI im Labor verstehen und nutzen: Wie K\u00fcnstliche Intelligenz Effizienz, Datenqualit\u00e4t und Entscheidungsprozesse verbessert.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.geniu.com\\\/de\\\/veranstaltung\\\/ki-im-labor-webinar-2026-09\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.geniu.com\\\/de\\\/veranstaltung\\\/ki-im-labor-webinar-2026-09\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.geniu.com\\\/de\\\/veranstaltung\\\/ki-im-labor-webinar-2026-09\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.geniu.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/image-1.png\",\"contentUrl\":\"https:\\\/\\\/www.geniu.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/image-1.png\",\"width\":1052,\"height\":676},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.geniu.com\\\/de\\\/veranstaltung\\\/ki-im-labor-webinar-2026-09\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.geniu.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veranstaltungen\",\"item\":\"https:\\\/\\\/www.geniu.com\\\/de\\\/veranstaltungen\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"KI im Labor \u2013 Webinar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.geniu.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.geniu.com\\\/de\\\/\",\"name\":\"Geniu\",\"description\":\"Weiterbildung und Beratung f\u00fcr Labore\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.geniu.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.geniu.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.geniu.com\\\/de\\\/#organization\",\"name\":\"Geniu GmbH\",\"alternateName\":\"Geniu\",\"url\":\"https:\\\/\\\/www.geniu.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.geniu.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Geniu GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.geniu.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Geniu-1574654296173059\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/geniu-gmbh\",\"https:\\\/\\\/www.xing.com\\\/companies\\\/geniu?literal=Geniu\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCotSWDP-a-Lbn2o0KbOpbBA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"KI im Labor \u2013 Webinar | Geniu","description":"KI im Labor verstehen und nutzen: Wie K\u00fcnstliche Intelligenz Effizienz, Datenqualit\u00e4t und Entscheidungsprozesse verbessert.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.geniu.com\/de\/veranstaltung\/ki-im-labor-webinar-2026-09\/","og_locale":"de_DE","og_type":"article","og_title":"KI im Labor \u2013 Webinar | Geniu","og_description":"KI im Labor verstehen und nutzen: Wie K\u00fcnstliche Intelligenz Effizienz, Datenqualit\u00e4t und Entscheidungsprozesse verbessert.","og_url":"https:\/\/www.geniu.com\/de\/veranstaltung\/ki-im-labor-webinar-2026-09\/","og_site_name":"Geniu","article_publisher":"https:\/\/www.facebook.com\/Geniu-1574654296173059","og_image":[{"width":1052,"height":676,"url":"https:\/\/www.geniu.com\/wp-content\/uploads\/2025\/10\/image-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.geniu.com\/de\/veranstaltung\/ki-im-labor-webinar-2026-09\/","url":"https:\/\/www.geniu.com\/de\/veranstaltung\/ki-im-labor-webinar-2026-09\/","name":"KI im Labor \u2013 Webinar | Geniu","isPartOf":{"@id":"https:\/\/www.geniu.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.geniu.com\/de\/veranstaltung\/ki-im-labor-webinar-2026-09\/#primaryimage"},"image":{"@id":"https:\/\/www.geniu.com\/de\/veranstaltung\/ki-im-labor-webinar-2026-09\/#primaryimage"},"thumbnailUrl":"https:\/\/www.geniu.com\/wp-content\/uploads\/2025\/10\/image-1.png","datePublished":"2025-11-28T23:10:56+00:00","description":"KI im Labor verstehen und nutzen: Wie K\u00fcnstliche Intelligenz Effizienz, Datenqualit\u00e4t und Entscheidungsprozesse verbessert.","breadcrumb":{"@id":"https:\/\/www.geniu.com\/de\/veranstaltung\/ki-im-labor-webinar-2026-09\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.geniu.com\/de\/veranstaltung\/ki-im-labor-webinar-2026-09\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.geniu.com\/de\/veranstaltung\/ki-im-labor-webinar-2026-09\/#primaryimage","url":"https:\/\/www.geniu.com\/wp-content\/uploads\/2025\/10\/image-1.png","contentUrl":"https:\/\/www.geniu.com\/wp-content\/uploads\/2025\/10\/image-1.png","width":1052,"height":676},{"@type":"BreadcrumbList","@id":"https:\/\/www.geniu.com\/de\/veranstaltung\/ki-im-labor-webinar-2026-09\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.geniu.com\/de\/"},{"@type":"ListItem","position":2,"name":"Veranstaltungen","item":"https:\/\/www.geniu.com\/de\/veranstaltungen\/"},{"@type":"ListItem","position":3,"name":"KI im Labor \u2013 Webinar"}]},{"@type":"WebSite","@id":"https:\/\/www.geniu.com\/de\/#website","url":"https:\/\/www.geniu.com\/de\/","name":"Geniu","description":"Weiterbildung und Beratung f\u00fcr Labore","publisher":{"@id":"https:\/\/www.geniu.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.geniu.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.geniu.com\/de\/#organization","name":"Geniu GmbH","alternateName":"Geniu","url":"https:\/\/www.geniu.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.geniu.com\/de\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Geniu GmbH"},"image":{"@id":"https:\/\/www.geniu.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Geniu-1574654296173059","https:\/\/www.linkedin.com\/company\/geniu-gmbh","https:\/\/www.xing.com\/companies\/geniu?literal=Geniu","https:\/\/www.youtube.com\/channel\/UCotSWDP-a-Lbn2o0KbOpbBA"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.geniu.com\/de\/wp-json\/wp\/v2\/tribe_events\/97370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.geniu.com\/de\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.geniu.com\/de\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.geniu.com\/de\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/www.geniu.com\/de\/wp-json\/wp\/v2\/tribe_events\/97370\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.geniu.com\/de\/wp-json\/wp\/v2\/media\/96114"}],"wp:attachment":[{"href":"https:\/\/www.geniu.com\/de\/wp-json\/wp\/v2\/media?parent=97370"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.geniu.com\/de\/wp-json\/wp\/v2\/tags?post=97370"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.geniu.com\/de\/wp-json\/wp\/v2\/tribe_events_cat?post=97370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}